{"id":24695,"date":"2015-10-27T00:49:14","date_gmt":"2015-10-26T23:49:14","guid":{"rendered":"https:\/\/hawiflex.de\/product\/arm-guard-3018-hx\/?lang=en"},"modified":"2015-11-11T08:39:16","modified_gmt":"2015-11-11T08:39:16","slug":"arm-guard-3018-hx","status":"publish","type":"product","link":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/","title":{"rendered":"Arm Guard 3018-Hx"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><b>Dimension: <\/b>60 x 60 x 280 mm<\/p>\n<p><b>Version:\u00a0<\/b>closed construction, with slot<\/p>\n<p><b>Modell No:<\/b> 3018-Hx<\/p>\n<p><b>Order No:<\/b> 1101596<\/p>\n","protected":false},"featured_media":28260,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1458],"product_tag":[1484],"class_list":{"0":"post-24695","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-arm-guard","7":"product_tag-schlosser-en","9":"first","10":"instock","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arm Guard 3018-Hx - Hawiflex by Contex<\/title>\n<meta name=\"description\" content=\"Dimension: 60 x 60 x 280 mm  Version:\u00a0closed construction, with slot  Modell No: 3018-Hx  Order No: 1101596 -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arm Guard 3018-Hx - Hawiflex by Contex\" \/>\n<meta property=\"og:description\" content=\"Dimension: 60 x 60 x 280 mm  Version:\u00a0closed construction, with slot  Modell No: 3018-Hx  Order No: 1101596 -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/\" \/>\n<meta property=\"og:site_name\" content=\"Hawiflex by Contex\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-11T08:39:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/3018_hx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1063\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/\",\"name\":\"Arm Guard 3018-Hx - Hawiflex by Contex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3018_hx.jpg\",\"datePublished\":\"2015-10-26T23:49:14+00:00\",\"dateModified\":\"2015-11-11T08:39:16+00:00\",\"description\":\"Dimension: 60 x 60 x 280 mm Version:\u00a0closed construction, with slot Modell No: 3018-Hx Order No: 1101596 -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3018_hx.jpg\",\"contentUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/3018_hx.jpg\",\"width\":1063,\"height\":1063,\"caption\":\"3018 hx\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-3018-hx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Find your mixing tools (catalog)\",\"item\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/online-catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arm Guard 3018-Hx\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\",\"name\":\"Hawiflex by Contex\",\"description\":\"Hawiflex\u00ae Moulded Parts, Coatings and Boards for Concrete Industry, for Pumps and much more\",\"publisher\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#organization\",\"name\":\"Hawiflex\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_hawiflex800.png\",\"contentUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_hawiflex800.png\",\"width\":800,\"height\":186,\"caption\":\"Hawiflex\"},\"image\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arm Guard 3018-Hx - Hawiflex by Contex","description":"Dimension: 60 x 60 x 280 mm  Version:\u00a0closed construction, with slot  Modell No: 3018-Hx  Order No: 1101596 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/","og_locale":"en_US","og_type":"article","og_title":"Arm Guard 3018-Hx - Hawiflex by Contex","og_description":"Dimension: 60 x 60 x 280 mm  Version:\u00a0closed construction, with slot  Modell No: 3018-Hx  Order No: 1101596 -","og_url":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/","og_site_name":"Hawiflex by Contex","article_modified_time":"2015-11-11T08:39:16+00:00","og_image":[{"width":1063,"height":1063,"url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/3018_hx.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/","url":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/","name":"Arm Guard 3018-Hx - Hawiflex by Contex","isPartOf":{"@id":"https:\/\/hawiflex.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/#primaryimage"},"image":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/#primaryimage"},"thumbnailUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/3018_hx.jpg","datePublished":"2015-10-26T23:49:14+00:00","dateModified":"2015-11-11T08:39:16+00:00","description":"Dimension: 60 x 60 x 280 mm Version:\u00a0closed construction, with slot Modell No: 3018-Hx Order No: 1101596 -","breadcrumb":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/#primaryimage","url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/3018_hx.jpg","contentUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/3018_hx.jpg","width":1063,"height":1063,"caption":"3018 hx"},{"@type":"BreadcrumbList","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-3018-hx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hawiflex.de\/en\/"},{"@type":"ListItem","position":2,"name":"Find your mixing tools (catalog)","item":"https:\/\/hawiflex.de\/en\/online-catalogue\/"},{"@type":"ListItem","position":3,"name":"Arm Guard 3018-Hx"}]},{"@type":"WebSite","@id":"https:\/\/hawiflex.de\/en\/#website","url":"https:\/\/hawiflex.de\/en\/","name":"Hawiflex by Contex","description":"Hawiflex\u00ae Moulded Parts, Coatings and Boards for Concrete Industry, for Pumps and much more","publisher":{"@id":"https:\/\/hawiflex.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hawiflex.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hawiflex.de\/en\/#organization","name":"Hawiflex","url":"https:\/\/hawiflex.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hawiflex.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2019\/03\/logo_hawiflex800.png","contentUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2019\/03\/logo_hawiflex800.png","width":800,"height":186,"caption":"Hawiflex"},"image":{"@id":"https:\/\/hawiflex.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product\/24695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/media\/28260"}],"wp:attachment":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/media?parent=24695"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_brand?post=24695"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_cat?post=24695"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_tag?post=24695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}