{"id":24577,"date":"2015-10-27T00:46:31","date_gmt":"2015-10-26T23:46:31","guid":{"rendered":"https:\/\/hawiflex.de\/product\/arm-guard-2375-hx-330-mm\/?lang=en"},"modified":"2015-11-11T10:17:01","modified_gmt":"2015-11-11T10:17:01","slug":"arm-guard-2375-hx-330-mm","status":"publish","type":"product","link":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/","title":{"rendered":"Arm Guard 2375-Hx 330 mm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><b>Dimension: <\/b>\u00d8 60 x 330 mm<\/p>\n<p><b>Version:\u00a0<\/b>closed construction, with slot<\/p>\n<p><b>Modell No:<\/b> 2375-Hx 330 mm<\/p>\n<p><b>Order No:<\/b> 1101345<\/p>\n","protected":false},"featured_media":28144,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1458],"product_tag":[1539,1503,1523,1560,1475,1496,1524,1484,1485],"class_list":{"0":"post-24577","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-arm-guard","7":"product_tag-damman-croes-en","8":"product_tag-elkon-en","9":"product_tag-ime-starmix-en","10":"product_tag-kabag-rtm-en","11":"product_tag-liebherr-en","12":"product_tag-lorev-en","13":"product_tag-omg-en","14":"product_tag-schlosser-en","15":"product_tag-sipe-en","17":"first","18":"instock","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arm Guard 2375-Hx 330 mm - Hawiflex by Contex<\/title>\n<meta name=\"description\" content=\"Dimension: \u00d8 60 x 330 mm  Version:\u00a0closed construction, with slot  Modell No: 2375-Hx 330 mm  Order No: 1101345 -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arm Guard 2375-Hx 330 mm - Hawiflex by Contex\" \/>\n<meta property=\"og:description\" content=\"Dimension: \u00d8 60 x 330 mm  Version:\u00a0closed construction, with slot  Modell No: 2375-Hx 330 mm  Order No: 1101345 -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Hawiflex by Contex\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-11T10:17:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/2375_hx_330.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1063\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/\",\"name\":\"Arm Guard 2375-Hx 330 mm - Hawiflex by Contex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/2375_hx_330.jpg\",\"datePublished\":\"2015-10-26T23:46:31+00:00\",\"dateModified\":\"2015-11-11T10:17:01+00:00\",\"description\":\"Dimension: \u00d8 60 x 330 mm Version:\u00a0closed construction, with slot Modell No: 2375-Hx 330 mm Order No: 1101345 -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/2375_hx_330.jpg\",\"contentUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/2375_hx_330.jpg\",\"width\":1063,\"height\":1063,\"caption\":\"2375 hx 330\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/product\\\/arm-guard-2375-hx-330-mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Find your mixing tools (catalog)\",\"item\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/online-catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arm Guard 2375-Hx 330 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\",\"name\":\"Hawiflex by Contex\",\"description\":\"Hawiflex\u00ae Moulded Parts, Coatings and Boards for Concrete Industry, for Pumps and much more\",\"publisher\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#organization\",\"name\":\"Hawiflex\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_hawiflex800.png\",\"contentUrl\":\"https:\\\/\\\/hawiflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_hawiflex800.png\",\"width\":800,\"height\":186,\"caption\":\"Hawiflex\"},\"image\":{\"@id\":\"https:\\\/\\\/hawiflex.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arm Guard 2375-Hx 330 mm - Hawiflex by Contex","description":"Dimension: \u00d8 60 x 330 mm  Version:\u00a0closed construction, with slot  Modell No: 2375-Hx 330 mm  Order No: 1101345 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/","og_locale":"en_US","og_type":"article","og_title":"Arm Guard 2375-Hx 330 mm - Hawiflex by Contex","og_description":"Dimension: \u00d8 60 x 330 mm  Version:\u00a0closed construction, with slot  Modell No: 2375-Hx 330 mm  Order No: 1101345 -","og_url":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/","og_site_name":"Hawiflex by Contex","article_modified_time":"2015-11-11T10:17:01+00:00","og_image":[{"width":1063,"height":1063,"url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/2375_hx_330.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/","url":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/","name":"Arm Guard 2375-Hx 330 mm - Hawiflex by Contex","isPartOf":{"@id":"https:\/\/hawiflex.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/#primaryimage"},"image":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/#primaryimage"},"thumbnailUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/2375_hx_330.jpg","datePublished":"2015-10-26T23:46:31+00:00","dateModified":"2015-11-11T10:17:01+00:00","description":"Dimension: \u00d8 60 x 330 mm Version:\u00a0closed construction, with slot Modell No: 2375-Hx 330 mm Order No: 1101345 -","breadcrumb":{"@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/#primaryimage","url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/2375_hx_330.jpg","contentUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2015\/10\/2375_hx_330.jpg","width":1063,"height":1063,"caption":"2375 hx 330"},{"@type":"BreadcrumbList","@id":"https:\/\/hawiflex.de\/en\/product\/arm-guard-2375-hx-330-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hawiflex.de\/en\/"},{"@type":"ListItem","position":2,"name":"Find your mixing tools (catalog)","item":"https:\/\/hawiflex.de\/en\/online-catalogue\/"},{"@type":"ListItem","position":3,"name":"Arm Guard 2375-Hx 330 mm"}]},{"@type":"WebSite","@id":"https:\/\/hawiflex.de\/en\/#website","url":"https:\/\/hawiflex.de\/en\/","name":"Hawiflex by Contex","description":"Hawiflex\u00ae Moulded Parts, Coatings and Boards for Concrete Industry, for Pumps and much more","publisher":{"@id":"https:\/\/hawiflex.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hawiflex.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hawiflex.de\/en\/#organization","name":"Hawiflex","url":"https:\/\/hawiflex.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hawiflex.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hawiflex.de\/wp-content\/uploads\/2019\/03\/logo_hawiflex800.png","contentUrl":"https:\/\/hawiflex.de\/wp-content\/uploads\/2019\/03\/logo_hawiflex800.png","width":800,"height":186,"caption":"Hawiflex"},"image":{"@id":"https:\/\/hawiflex.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product\/24577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/media\/28144"}],"wp:attachment":[{"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/media?parent=24577"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_brand?post=24577"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_cat?post=24577"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hawiflex.de\/en\/wp-json\/wp\/v2\/product_tag?post=24577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}